{"id":22288,"date":"2023-04-18T00:00:00","date_gmt":"2023-04-18T03:00:00","guid":{"rendered":"https:\/\/site-novo.dattos.com.br\/caso-marisa\/"},"modified":"2024-10-11T21:27:23","modified_gmt":"2024-10-12T00:27:23","slug":"caso-marisa","status":"publish","type":"post","link":"https:\/\/www.dattos.com.br\/es\/blog\/caso-marisa\/","title":{"rendered":"Caso Marisa: d\u00edvidas, ren\u00fancias e reestrutura\u00e7\u00e3o financeira"},"content":{"rendered":"\n<p>Caso Marisa: j\u00e1 era de se esperar que ap\u00f3s a divulga\u00e7\u00e3o do <a href=\"https:\/\/www.dattos.com.br\/blog\/rombo-contabil\/\" target=\"_blank\" rel=\"noreferrer noopener\"><b>rombo financeiro na varejista Americanas<\/b><\/a> outros casos parecidos come\u00e7assem a ser expostos na m\u00eddia.<\/p>\n\n\n\n<p>E como voc\u00ea j\u00e1 deve ter visto, a \u00faltima v\u00edtima de queda na Bolsa foi a rede de moda feminina Marisa, cujas a\u00e7\u00f5es despencaram 18,87% no dia 9 de fevereiro, entrando no grupo de \u201cpenny stocks\u201d \u2013 a\u00e7\u00f5es que valem menos do que R$ 1.<\/p>\n\n\n\n<p>Assustadoramente, \u00e9 a primeira vez que suas a\u00e7\u00f5es recuam desde que estreou em 2007.&nbsp;<\/p>\n\n\n\n<p>Entretanto, o problema n\u00e3o come\u00e7ou a\u00ed: segundo \u00faltimo balan\u00e7o divulgado, no terceiro trimestre de 2022, a Marisa deve cerca de R$ 600 milh\u00f5es devido ao aumento das despesas com os bancos como Bradesco, Safra, Ita\u00fa e Caixa, isso, al\u00e9m de <b>problemas de concilia\u00e7\u00e3o<\/b>, por causa de uma uma queda de 43,8% nas vendas digitais em 2021.<\/p>\n\n\n\n<p>Agora, a d\u00edvida se encontra em renegocia\u00e7\u00e3o, mas com o esc\u00e2ndalo do rombo financeiro da Americanas, os bancos ficaram cautelosos ao ceder cr\u00e9dito \u00e0s empresas do setor varejista, como a Marisa.<\/p>\n\n\n\n<p>E claro, ap\u00f3s o caso cr\u00edtico na Bolsa, a Marisa decidiu de vez que era hora de passar por uma s\u00e9ria reestrutura\u00e7\u00e3o com o objetivo de lidar com o problema \u2014 <strong>s\u00f3 essa not\u00edcia fez suas a\u00e7\u00f5es ca\u00edrem 42%<\/strong>.&nbsp;<\/p>\n\n\n\n<p>Tanto que, nos \u00faltimos dias, a Marisa anunciou a ren\u00fancia do comando de seu Conselho de Administra\u00e7\u00e3o, que passou de Marcelo Doll Martinelli, ap\u00f3s sua ren\u00fancia, para Jo\u00e3o Pinheiro Nogueira Batista, ex-diretor financeiro da Petrobras, al\u00e9m de contratar a BR Partners para auxiliar na renegocia\u00e7\u00e3o da d\u00edvida milion\u00e1ria.<\/p>\n\n\n\n<p>Apesar do problema n\u00e3o ser como o das Americanas, cuja d\u00edvida financeira foi maior que o pr\u00f3prio pre\u00e7o de mercado da varejista, o Caso Marisa n\u00e3o deixa as tens\u00f5es de lado, uma vez que promove desconfian\u00e7a entre bancos e gestores.<\/p>\n\n\n\n<p>Por isso, \u00e9 necess\u00e1rio que as grandes empresas fiquem atentas, j\u00e1 que \u00e9 um risco que n\u00e3o se limita apenas a essas varejistas.<\/p>\n\n\n\n<p>Entenda!<style>\/*! elementor - v3.11.5 - 14-03-2023 *\/&amp;lt;br \/>&lt;br>.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Caso Marisa: por que grandes empresas est\u00e3o sujeitas ao risco?<\/h2>\n\n\n\n<p>Se voc\u00ea \u00e9 o gestor ou o analista cont\u00e1bil de uma grande empresa, entende na pr\u00e1tica a bagun\u00e7a que ficou o mercado ap\u00f3s o caso da Americanas.<\/p>\n\n\n\n<p>Afinal, empresas que t\u00eam endividamento elevado ou dificuldade para gerar receita est\u00e3o encontrando dificuldades para resolver o problema, j\u00e1 que a taxa Selic est\u00e1 nas alturas e muitos bancos se recusam a ajudar \u2014 mesmo tendo uma capacidade de liquidez enorme para absorver os danos.<\/p>\n\n\n\n<p><b>Isso porque a desconfian\u00e7a est\u00e1 cada vez maior! <\/b>Por isso, empresas como a Marisa, que h\u00e1 anos tenta reestruturar suas opera\u00e7\u00f5es e financiar suas d\u00edvidas, se v\u00eaem em um cen\u00e1rio extremamente deprimente.&nbsp;<\/p>\n\n\n\n<p>Mas, apesar da situa\u00e7\u00e3o do Caso Marisa ser dif\u00edcil, \u00e9 poss\u00edvel contorn\u00e1-la.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como um bom Fechamento Cont\u00e1bil pode evitar rombos financeiros?<\/h2>\n\n\n\n<p>Na rotina dos times cont\u00e1beis, o Fechamento Cont\u00e1bil nada mais \u00e9 do que identificar e analisar todas as movimenta\u00e7\u00f5es financeiras da empresa, gerando um relat\u00f3rio completo e seguro aos gestores para que tomem as melhores decis\u00f5es e definam qual dire\u00e7\u00e3o o neg\u00f3cio deve tomar.<\/p>\n\n\n\n<p><b>Inclusive, aqui voc\u00ea pode ter um <a href=\"https:\/\/www.dattos.com.br\/blog\/fechamento-contabil\/\" target=\"_blank\" rel=\"noreferrer noopener\">guia completo sobre fechamento cont\u00e1bil<\/a>.<\/b><\/p>\n\n\n\n<p>Ou seja, \u00e9 um processo necess\u00e1rio principalmente para empresas de grande porte como a Marisa, cujas informa\u00e7\u00f5es financeiras precisam ser analisadas constantemente a fim de evitar rombos financeiros.<\/p>\n\n\n\n<p>Entretanto, vimos com o Caso Marisa que n\u00e3o foi isso o que aconteceu.<\/p>\n\n\n\n<p>\u00c9 prov\u00e1vel que diversos dados cont\u00e1beis tenham se perdido ao longo dos fechamentos , o que desestabilizou a empresa na cria\u00e7\u00e3o de uma estrat\u00e9gia pr\u00e1tica de resolu\u00e7\u00e3o do problema \u2014 <b>uma consequ\u00eancia direta de um processo manual<\/b>.<\/p>\n\n\n\n<p>A boa not\u00edcia \u00e9 que hoje em dia j\u00e1 existem plataformas especializadas no processo de Fechamento Cont\u00e1bil que garantem a seguran\u00e7a das informa\u00e7\u00f5es e uma gest\u00e3o otimizada do processo.<\/p>\n\n\n\n<p>E se voc\u00ea procura solu\u00e7\u00f5es a fim de evitar destinos tr\u00e1gicos como os das varejistas citadas, a Dattos pode ser a melhor op\u00e7\u00e3o.<\/p>\n\n\n\n<p>Na Dattos, trabalhamos reduzindo o tempo gasto em <a href=\"https:\/\/www.dattos.com.br\/blog\/riscos-no-fechamento-contabil\/\" target=\"_blank\" rel=\"noreferrer noopener\"><b>fechamentos financeiros<\/b><\/a> em at\u00e9 70%, al\u00e9m de garantirmos a seguran\u00e7a dos dados coletados para os processos de auditoria e uma concilia\u00e7\u00e3o feita em poucos minutos. Tudo isso em uma \u00fanica plataforma, onde voc\u00ea poder\u00e1 ter uma vis\u00e3o ampla de seus dados e uma gest\u00e3o focada.<a role=\"button\" href=\"https:\/\/conteudo.dattos.com.br\/lp-guia-definitivo-para-um-fechamento-contabil-assertivo\" target=\"_blank\" rel=\"noopener\"><br><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Caso Marisa assusta devido a d\u00edvida de R$ 600 milh\u00f5es da varejista e exp\u00f5e momento dif\u00edcil para as grandes empresas. Saiba mais!<\/p>","protected":false},"author":3,"featured_media":22560,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[60],"tags":[229,48,76,88],"class_list":["post-22288","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-governanca","tag-caso-marisa","tag-dattos","tag-elementor","tag-governanca"],"_links":{"self":[{"href":"https:\/\/www.dattos.com.br\/es\/wp-json\/wp\/v2\/posts\/22288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dattos.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dattos.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dattos.com.br\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dattos.com.br\/es\/wp-json\/wp\/v2\/comments?post=22288"}],"version-history":[{"count":0,"href":"https:\/\/www.dattos.com.br\/es\/wp-json\/wp\/v2\/posts\/22288\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dattos.com.br\/es\/wp-json\/wp\/v2\/media\/22560"}],"wp:attachment":[{"href":"https:\/\/www.dattos.com.br\/es\/wp-json\/wp\/v2\/media?parent=22288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dattos.com.br\/es\/wp-json\/wp\/v2\/categories?post=22288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dattos.com.br\/es\/wp-json\/wp\/v2\/tags?post=22288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}